{"id":14462,"date":"2026-06-24T07:32:04","date_gmt":"2026-06-24T07:32:04","guid":{"rendered":"https:\/\/easyledstore.it\/?post_type=product&#038;p=14462"},"modified":"2026-06-24T07:52:53","modified_gmt":"2026-06-24T07:52:53","slug":"flex-neon-split-12mm-12v-9w-m-10-metri","status":"publish","type":"product","link":"https:\/\/easyledstore.it\/de\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/","title":{"rendered":"Flex Neon Split 12mm &#8211; 12V 9W\/m 10 Metri"},"content":{"rendered":"<p data-start=\"562\" data-end=\"784\">Die <strong data-start=\"565\" data-end=\"588\">flex neon split LED<\/strong> 12V \u00e8 una soluzione moderna e flessibile per realizzare illuminazioni decorative continue e uniformi. Grazie alla sua struttura innovativa, permette di creare linee luminose senza punti visibili.<\/p>\n<p data-start=\"786\" data-end=\"949\">Questo prodotto \u00e8 ideale per insegne luminose, decorazioni e installazioni architettoniche. Inoltre, si adatta facilmente a superfici curve e forme personalizzate.<\/p>\n<hr data-start=\"951\" data-end=\"954\" \/>\n<h2 data-section-id=\"kkpqx7\" data-start=\"956\" data-end=\"1000\"><span role=\"text\"><strong data-start=\"959\" data-end=\"1000\">Flex neon split LED wei\u00df und farbig<\/strong><\/span><\/h2>\n<p data-start=\"1002\" data-end=\"1096\">Il flex neon split LED \u00e8 disponibile in due varianti principali, pensate per esigenze diverse.<\/p>\n<h3 data-section-id=\"11l61ox\" data-start=\"1098\" data-end=\"1121\"><span role=\"text\"><strong data-start=\"1102\" data-end=\"1121\">Wei\u00dfe Version<\/strong><\/span><\/h3>\n<p data-start=\"1122\" data-end=\"1356\">La versione bianco del flex neon split LED \u00e8 perfetta per progetti che richiedono un\u2019illuminazione pulita e professionale. Viene utilizzata spesso in insegne commerciali e ambienti moderni dove \u00e8 importante una resa luminosa uniforme.<\/p>\n<h3 data-section-id=\"1bpluig\" data-start=\"1358\" data-end=\"1383\"><span role=\"text\"><strong data-start=\"1362\" data-end=\"1383\">Farbige Version<\/strong><\/span><\/h3>\n<p data-start=\"1384\" data-end=\"1611\">La versione colorati del flex neon split LED \u00e8 ideale per applicazioni decorative. Consente di creare effetti visivi pi\u00f9 dinamici e accattivanti. Per questo motivo \u00e8 molto utilizzata in vetrine, eventi e installazioni creative.<\/p>\n<hr data-start=\"1613\" data-end=\"1616\" \/>\n<h2 data-section-id=\"uas5rj\" data-start=\"1618\" data-end=\"1657\"><span role=\"text\"><strong data-start=\"1621\" data-end=\"1657\">Vorteile von flex neon split LED<\/strong><\/span><\/h2>\n<p data-start=\"1659\" data-end=\"1745\">Die flex neon split LED bietet zahlreiche Vorteile gegen\u00fcber herk\u00f6mmlichen LED-Streifen:<\/p>\n<ul data-start=\"1747\" data-end=\"1894\">\n<li data-section-id=\"17m37yk\" data-start=\"1747\" data-end=\"1785\">Dauerlicht ohne sichtbare Punkte<\/li>\n<li data-section-id=\"1ed0e7u\" data-start=\"1786\" data-end=\"1810\">elevata flessibilit\u00e0<\/li>\n<li data-section-id=\"f2359z\" data-start=\"1811\" data-end=\"1837\">einfache Installation<\/li>\n<li data-section-id=\"10iesu7\" data-start=\"1838\" data-end=\"1862\">hervorragende \u00e4sthetische Leistung<\/li>\n<li data-section-id=\"jhiv16\" data-start=\"1863\" data-end=\"1894\">Innen- und Au\u00dfeneinsatz<\/li>\n<\/ul>\n<p data-start=\"1896\" data-end=\"1981\">Dank dieser Eigenschaften ist es eine vielseitige und professionelle L\u00f6sung.<\/p>\n<hr data-start=\"1983\" data-end=\"1986\" \/>\n<h2 data-section-id=\"148zodt\" data-start=\"1988\" data-end=\"2019\"><span role=\"text\"><strong data-start=\"1991\" data-end=\"2019\">Technische Daten<\/strong><\/span><\/h2>\n<ul data-start=\"2021\" data-end=\"2209\">\n<li data-section-id=\"1ael8zr\" data-start=\"2021\" data-end=\"2043\">Stromversorgung: 12V<\/li>\n<li data-section-id=\"12tb09r\" data-start=\"2044\" data-end=\"2081\">Flexible und widerstandsf\u00e4hige Struktur<\/li>\n<li data-section-id=\"v51qmu\" data-start=\"2082\" data-end=\"2110\">Gleichm\u00e4\u00dfiges, kontinuierliches Licht<\/li>\n<li data-section-id=\"vi5er\" data-start=\"2111\" data-end=\"2156\">Einfache Installation auf verschiedenen Oberfl\u00e4chen<\/li>\n<li data-section-id=\"jpptrk\" data-start=\"2157\" data-end=\"2209\">Verwendung f\u00fcr dekorative und professionelle Projekte<\/li>\n<\/ul>\n<p data-start=\"2211\" data-end=\"2292\">Il flex neon split LED \u00e8 progettato per garantire prestazioni costanti nel tempo.<\/p>\n<hr data-start=\"2294\" data-end=\"2297\" \/>\n<h2 data-section-id=\"12om5lv\" data-start=\"2299\" data-end=\"2329\"><span role=\"text\"><strong data-start=\"2302\" data-end=\"2329\">Wichtigste Anwendungen<\/strong><\/span><\/h2>\n<p data-start=\"2331\" data-end=\"2406\">Die Flex-Neon-Split-LED wird in vielen verschiedenen Zusammenh\u00e4ngen verwendet, unter anderem:<\/p>\n<ul data-start=\"2408\" data-end=\"2544\">\n<li data-section-id=\"1ac52bj\" data-start=\"2408\" data-end=\"2428\">beleuchtete Zeichen<\/li>\n<li data-section-id=\"wsb9pp\" data-start=\"2429\" data-end=\"2455\">Architekturprofile<\/li>\n<li data-section-id=\"g4grjx\" data-start=\"2456\" data-end=\"2490\">Innen- und Au\u00dfendekoration<\/li>\n<li data-section-id=\"1ld3jd6\" data-start=\"2491\" data-end=\"2514\">Schaufenster<\/li>\n<li data-section-id=\"wxo7b0\" data-start=\"2515\" data-end=\"2544\">szenische Darstellungen<\/li>\n<\/ul>\n<p data-start=\"2546\" data-end=\"2619\">La sua versatilit\u00e0 lo rende adatto sia a progetti semplici che complessi.<\/p>\n<hr data-start=\"2621\" data-end=\"2624\" \/>\n<h2 data-section-id=\"1c22e95\" data-start=\"2626\" data-end=\"2664\"><span role=\"text\"><strong data-start=\"2629\" data-end=\"2664\">Schnelle und einfache Installation<\/strong><\/span><\/h2>\n<p data-start=\"2666\" data-end=\"2829\">Uno dei punti di forza del flex neon split LED \u00e8 la facilit\u00e0 di installazione. Pu\u00f2 essere applicato su diverse superfici e adattato a forme curve senza difficolt\u00e0.<\/p>\n<p data-start=\"2831\" data-end=\"2960\">Dar\u00fcber hinaus verk\u00fcrzt das flexible Design die Montagezeit und ist somit ideal f\u00fcr schnelle professionelle Installationen.<\/p>\n<hr data-start=\"2962\" data-end=\"2965\" \/>\n<h2 data-section-id=\"urigw2\" data-start=\"2967\" data-end=\"3013\"><span role=\"text\"><strong data-start=\"2970\" data-end=\"3013\">Perch\u00e9 scegliere il flex neon split LED<\/strong><\/span><\/h2>\n<p data-start=\"3015\" data-end=\"3188\">Il flex neon split LED rappresenta una soluzione affidabile per chi cerca un\u2019illuminazione decorativa moderna. Infatti, combina estetica, flessibilit\u00e0 e prestazioni elevate.<\/p>\n<p data-start=\"3190\" data-end=\"3303\">Inoltre, la possibilit\u00e0 di scegliere tra versione bianco e colorati lo rende adatto a qualsiasi tipo di progetto.<\/p>\n<hr data-start=\"3305\" data-end=\"3308\" \/>\n<h2 data-section-id=\"pjat1f\" data-start=\"3310\" data-end=\"3328\"><span role=\"text\"><strong data-start=\"3313\" data-end=\"3328\">Schlussfolgerung<\/strong><\/span><\/h2>\n<p data-start=\"3330\" data-end=\"3595\">Il flex neon split LED \u00e8 una scelta ideale per realizzare installazioni luminose continue e di grande impatto visivo. Grazie alle sue caratteristiche tecniche e alla sua versatilit\u00e0, \u00e8 sempre pi\u00f9 utilizzato nel settore dell\u2019illuminazione decorativa e professionale.<\/p>","protected":false},"excerpt":{"rendered":"<p>Flex neon split LED 12V, erh\u00e4ltlich in wei\u00dfer und farbiger Ausf\u00fchrung, ideal f\u00fcr gleichm\u00e4\u00dfige und dekorative Beleuchtung.<\/p>","protected":false},"featured_media":13195,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[174,460,283,495],"product_tag":[],"class_list":["post-14462","product","type-product","status-publish","has-post-thumbnail","product_cat-flex","product_cat-prodotti-da-interno","product_cat-split-led-flex","product_cat-tutti-i-prodotti","pa_colore-10000k","pa_colore-3000k","pa_colore-4000k","pa_colore-6500k","pa_colore-blue","pa_colore-green","pa_colore-lemon","pa_colore-red","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Flex Neon Split 12mm - 12V 9W\/m 10 Metri - Easy LED Store<\/title>\n<meta name=\"description\" content=\"Flex neon split LED 12V disponibile in versione bianco e colorati. Flessibile, uniforme e ideale per insegne e decorazioni.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easyledstore.it\/de\/produkt\/flex-neon-split-12mm-12v-9w-m-10-metri\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Flex Neon Split 12mm - 12V 9W\/m 10 Metri - Easy LED Store\" \/>\n<meta property=\"og:description\" content=\"Flex neon split LED 12V disponibile in versione bianco e colorati. Flessibile, uniforme e ideale per insegne e decorazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easyledstore.it\/de\/produkt\/flex-neon-split-12mm-12v-9w-m-10-metri\/\" \/>\n<meta property=\"og:site_name\" content=\"Easy LED Store\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/easyledstore\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T07:52:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/03\/SPLIT-6-WHITE.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/\",\"name\":\"Flex Neon Split 12mm - 12V 9W\\\/m 10 Metri - Easy LED Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/SPLIT-6-WHITE.webp\",\"datePublished\":\"2026-06-24T07:32:04+00:00\",\"dateModified\":\"2026-06-24T07:52:53+00:00\",\"description\":\"Flex neon split LED 12V disponibile in versione bianco e colorati. Flessibile, uniforme e ideale per insegne e decorazioni.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/SPLIT-6-WHITE.webp\",\"contentUrl\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/SPLIT-6-WHITE.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/prodotto\\\/flex-neon-split-12mm-12v-9w-m-10-metri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/easyledstore.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/easyledstore.it\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Flex Neon Split 12mm &#8211; 12V 9W\\\/m 10 Metri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#website\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/\",\"name\":\"Easy LED Store\",\"description\":\"Tutto per le insegne luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easyledstore.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#organization\",\"name\":\"Easy LED Store\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EasyLed-BY-DIRECTAGROUP.png\",\"contentUrl\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EasyLed-BY-DIRECTAGROUP.png\",\"width\":1500,\"height\":367,\"caption\":\"Easy LED Store\"},\"image\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/easyledstore\",\"https:\\\/\\\/www.instagram.com\\\/easyledstore.it\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCadmBU3-vC9_KmxdkWDh8IQ\",\"https:\\\/\\\/wa.me\\\/393532091766\",\"https:\\\/\\\/www.tiktok.com\\\/@easyledstore.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Flex Neon Split 12mm - 12V 9W\/m 10 Metri - Easy LED Store","description":"Flex Neon Split LED 12V in wei\u00dfer und farbiger Ausf\u00fchrung. Flexibel, einheitlich und ideal f\u00fcr Schilder und Dekorationen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easyledstore.it\/de\/produkt\/flex-neon-split-12mm-12v-9w-m-10-metri\/","og_locale":"de_DE","og_type":"article","og_title":"Flex Neon Split 12mm - 12V 9W\/m 10 Metri - Easy LED Store","og_description":"Flex neon split LED 12V disponibile in versione bianco e colorati. Flessibile, uniforme e ideale per insegne e decorazioni.","og_url":"https:\/\/easyledstore.it\/de\/produkt\/flex-neon-split-12mm-12v-9w-m-10-metri\/","og_site_name":"Easy LED Store","article_publisher":"https:\/\/www.facebook.com\/easyledstore","article_modified_time":"2026-06-24T07:52:53+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/03\/SPLIT-6-WHITE.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/","url":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/","name":"Flex Neon Split 12mm - 12V 9W\/m 10 Metri - Easy LED Store","isPartOf":{"@id":"https:\/\/easyledstore.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/#primaryimage"},"image":{"@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/#primaryimage"},"thumbnailUrl":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/03\/SPLIT-6-WHITE.webp","datePublished":"2026-06-24T07:32:04+00:00","dateModified":"2026-06-24T07:52:53+00:00","description":"Flex Neon Split LED 12V in wei\u00dfer und farbiger Ausf\u00fchrung. Flexibel, einheitlich und ideal f\u00fcr Schilder und Dekorationen.","breadcrumb":{"@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/#primaryimage","url":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/03\/SPLIT-6-WHITE.webp","contentUrl":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/03\/SPLIT-6-WHITE.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/easyledstore.it\/prodotto\/flex-neon-split-12mm-12v-9w-m-10-metri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/easyledstore.it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/easyledstore.it\/shop\/"},{"@type":"ListItem","position":3,"name":"Flex Neon Split 12mm &#8211; 12V 9W\/m 10 Metri"}]},{"@type":"WebSite","@id":"https:\/\/easyledstore.it\/#website","url":"https:\/\/easyledstore.it\/","name":"Einfacher LED-Speicher","description":"Alles f\u00fcr die Beschilderung","publisher":{"@id":"https:\/\/easyledstore.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easyledstore.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/easyledstore.it\/#organization","name":"Einfacher LED-Speicher","url":"https:\/\/easyledstore.it\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/easyledstore.it\/#\/schema\/logo\/image\/","url":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/04\/EasyLed-BY-DIRECTAGROUP.png","contentUrl":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/04\/EasyLed-BY-DIRECTAGROUP.png","width":1500,"height":367,"caption":"Easy LED Store"},"image":{"@id":"https:\/\/easyledstore.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/easyledstore","https:\/\/www.instagram.com\/easyledstore.it","https:\/\/www.youtube.com\/channel\/UCadmBU3-vC9_KmxdkWDh8IQ","https:\/\/wa.me\/393532091766","https:\/\/www.tiktok.com\/@easyledstore.it"]}]}},"_links":{"self":[{"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/product\/14462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/comments?post=14462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/media\/13195"}],"wp:attachment":[{"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/media?parent=14462"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/product_brand?post=14462"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/product_cat?post=14462"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/easyledstore.it\/de\/wp-json\/wp\/v2\/product_tag?post=14462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}