{"id":177,"count":5,"description":"<div class=\"flex flex-col text-sm pb-25\">\r\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\r\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\r\n<div class=\"flex max-w-full flex-col grow\">\r\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\">\r\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\r\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\r\nI Dimmer LED per regolazione luminosa consentono di gestire con precisione l\u2019intensit\u00e0 delle luci LED in insegne, moduli, barre e strip. Permettono di creare l\u2019atmosfera desiderata, risparmiare energia e proteggere i componenti LED, garantendo prestazioni ottimali. I dimmer LED assicurano affidabilit\u00e0 e lunga durata per progetti di illuminazione professionale.\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\r\n<div class=\"mt-3 w-full empty:hidden\">\r\n<div class=\"text-center\"><\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div class=\"pointer-events-none h-px w-px absolute bottom-0\"><\/div>","link":"https:\/\/easyledstore.it\/es\/product-category\/centraline\/dimmer\/","name":"Regulador de intensidad","slug":"atenuador","taxonomy":"product_cat","parent":158,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dimmer Archivi - Easy LED Store<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/easyledstore.it\/es\/categoria-de-productos\/unidades-de-control\/atenuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimmer Archivi - Easy LED Store\" \/>\n<meta property=\"og:description\" content=\"I Dimmer LED per regolazione luminosa consentono di gestire con precisione l\u2019intensit\u00e0 delle luci LED in insegne, moduli, barre e strip. Permettono di creare l\u2019atmosfera desiderata, risparmiare energia e proteggere i componenti LED, garantendo prestazioni ottimali. I dimmer LED assicurano affidabilit\u00e0 e lunga durata per progetti di illuminazione professionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/easyledstore.it\/es\/categoria-de-productos\/unidades-de-control\/atenuador\/\" \/>\n<meta property=\"og:site_name\" content=\"Easy LED Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/product-category\\\/centraline\\\/dimmer\\\/\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/product-category\\\/centraline\\\/dimmer\\\/\",\"name\":\"Dimmer Archivi - Easy LED Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/product-category\\\/centraline\\\/dimmer\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/product-category\\\/centraline\\\/dimmer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/easyledstore.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centraline\",\"item\":\"https:\\\/\\\/easyledstore.it\\\/product-category\\\/centraline\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dimmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#website\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/\",\"name\":\"Easy LED Store\",\"description\":\"Tutto per le insegne luminose\",\"publisher\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/easyledstore.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#organization\",\"name\":\"Easy LED Store\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EasyLed-BY-DIRECTAGROUP.png\",\"contentUrl\":\"https:\\\/\\\/easyledstore.it\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/EasyLed-BY-DIRECTAGROUP.png\",\"width\":1500,\"height\":367,\"caption\":\"Easy LED Store\"},\"image\":{\"@id\":\"https:\\\/\\\/easyledstore.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/easyledstore\",\"https:\\\/\\\/www.instagram.com\\\/easyledstore.it\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCadmBU3-vC9_KmxdkWDh8IQ\",\"https:\\\/\\\/wa.me\\\/393532091766\",\"https:\\\/\\\/www.tiktok.com\\\/@easyledstore.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dimmer Archivos - Easy LED Store","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/easyledstore.it\/es\/categoria-de-productos\/unidades-de-control\/atenuador\/","og_locale":"es_ES","og_type":"article","og_title":"Dimmer Archivi - Easy LED Store","og_description":"I Dimmer LED per regolazione luminosa consentono di gestire con precisione l\u2019intensit\u00e0 delle luci LED in insegne, moduli, barre e strip. Permettono di creare l\u2019atmosfera desiderata, risparmiare energia e proteggere i componenti LED, garantendo prestazioni ottimali. I dimmer LED assicurano affidabilit\u00e0 e lunga durata per progetti di illuminazione professionale.","og_url":"https:\/\/easyledstore.it\/es\/categoria-de-productos\/unidades-de-control\/atenuador\/","og_site_name":"Easy LED Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/easyledstore.it\/product-category\/centraline\/dimmer\/","url":"https:\/\/easyledstore.it\/product-category\/centraline\/dimmer\/","name":"Dimmer Archivos - Easy LED Store","isPartOf":{"@id":"https:\/\/easyledstore.it\/#website"},"breadcrumb":{"@id":"https:\/\/easyledstore.it\/product-category\/centraline\/dimmer\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/easyledstore.it\/product-category\/centraline\/dimmer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/easyledstore.it\/"},{"@type":"ListItem","position":2,"name":"Centraline","item":"https:\/\/easyledstore.it\/product-category\/centraline\/"},{"@type":"ListItem","position":3,"name":"Dimmer"}]},{"@type":"WebSite","@id":"https:\/\/easyledstore.it\/#website","url":"https:\/\/easyledstore.it\/","name":"Tienda Easy LED","description":"Todo para la se\u00f1alizaci\u00f3n","publisher":{"@id":"https:\/\/easyledstore.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/easyledstore.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/easyledstore.it\/#organization","name":"Tienda Easy LED","url":"https:\/\/easyledstore.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/easyledstore.it\/#\/schema\/logo\/image\/","url":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/04\/EasyLed-BY-DIRECTAGROUP.png","contentUrl":"https:\/\/easyledstore.it\/wp-content\/uploads\/2026\/04\/EasyLed-BY-DIRECTAGROUP.png","width":1500,"height":367,"caption":"Easy LED Store"},"image":{"@id":"https:\/\/easyledstore.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/easyledstore","https:\/\/www.instagram.com\/easyledstore.it","https:\/\/www.youtube.com\/channel\/UCadmBU3-vC9_KmxdkWDh8IQ","https:\/\/wa.me\/393532091766","https:\/\/www.tiktok.com\/@easyledstore.it"]}]}},"_links":{"self":[{"href":"https:\/\/easyledstore.it\/es\/wp-json\/wp\/v2\/product_cat\/177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/easyledstore.it\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/easyledstore.it\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/easyledstore.it\/es\/wp-json\/wp\/v2\/product_cat\/158"}],"wp:post_type":[{"href":"https:\/\/easyledstore.it\/es\/wp-json\/wp\/v2\/product?product_cat=177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}